{"id":23541,"date":"2020-03-26T10:48:50","date_gmt":"2020-03-26T09:48:50","guid":{"rendered":"https:\/\/www.neusta-ds.de\/blog\/?p=23541"},"modified":"2020-03-26T11:22:30","modified_gmt":"2020-03-26T10:22:30","slug":"daten-inhalte","status":"publish","type":"post","link":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/","title":{"rendered":"Daten. Inhalte."},"content":{"rendered":"<section class=\"vc_row wpb_row vc_row-fluid  vc_custom_1507701938070 wow fadeIn\"><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-10 vc_col-xs-12\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><div class=\"last-paragraph-no-margin\"><h6>Wer als Produzent von Content diesen regelm\u00e4\u00dfig auf seinen Erfolg \u00fcberpr\u00fcft, wird um Ver\u00e4nderungen nicht herumkommen. Gleiches gilt fu\u0308r Destinationen, die \u00fcber Daten heute immer mehr \u00fcber ihre G\u00e4ste erfahren. Doch wohin f\u00fchrt das eigentlich?<\/h6>\n<p>Wissen Sie, was der Niedergang der alten Medienwelt mit der Digitalisierung zu tun hat? Nichts. Vielmehr sind die immensen Auflagenverluste der vergangenen gut zehn Jahre und die sich daran anschlie\u00dfende Unf\u00e4higkeit, die \u201everloren gegangenen Leser\u201c in den Digitalangeboten wieder f\u00fcr sich zu gewinnen, die Geschichte einer Entfremdung. Einer Entfremdung zwischen jenen, die Inhalte produzieren und jenen, die sie lesen (sollen).<\/p>\n<p>Ich durfte das als Redaktionsleiter Reise bei der Funke Mediengruppe zwischen 2009 und 2016 in NRW hautnah miterleben. Wenn wir aus dem Reisebereich bei den Kollegen anderer Redaktionen anklopften, ob man dort f\u00fcr uns mal eine Leserreise begleiten k\u00f6nnte, um dar\u00fcber zu schreiben, kam die Absage stets prompt. Einen oder gar mehrere Tage mit den eigenen Lesern zu verbringen \u2013 f\u00fcr die allermeisten Redakteure ein Alptraum! Und so kommt es, dass Edelfedern \u00fcber Theaterpremieren schreiben, die zwar bei den Kollegen in der eigenen Redaktion Begeisterungsst\u00fcrme ausl\u00f6sen, die Leserschaft aber nicht interessieren. Deswegen entstehen Gastrokritiken von Lokalen, in die sich der Gro\u00dfteil der eigenen Abonnenten nie verirrt. Deswegen setzen Blattmacher bis heute viele Themen, die an den Interessen der eigenen Leserschaft komplett vorbeigehen.<\/p>\n<blockquote class=\"border-color-deep-pink\"><p>\nDie Digitalisierung ist nicht schuld daran, dass viele klassische Medien so massiv an Bedeutung verlieren.\n<\/p><\/blockquote>\n<p>Und dass sich immer mehr Menschen heute online an ihren tats\u00e4chlichen Bed\u00fcrfnissen orientiert informieren k\u00f6nnen, ist nur einseitig betrachtet das Surfen in der \u201eMeinungsblase\u201c, sondern zun\u00e4chst der gr\u00f6\u00dfte mediale Fortschritt der vergangenen Jahrzehnte. Arbeitet die Touristik nicht gerade selbst mit Hochdruck im Zuge der Open Data-Thematik daran, potenziellen G\u00e4sten nur noch genau die zu deren Interessen passenden Angebote auszuspielen?<\/p>\n<p>Reportingtools verraten uns heute schon mehr \u00fcber unsere Kunden bzw. Leser, als es braucht, um die eigene Strategie regelm\u00e4\u00dfig zu \u00fcberpr\u00fcfen. Wer als Entscheider bereit ist, immer mal wieder \u00fcber seinen eigenen Schatten zu springen, f\u00fcr den ist die Digitalisierung deshalb ein Segen. Eine Destination, die getrieben vom eigenen Selbstbild eine Kultur- und Genussregion sein m\u00f6chte, obwohl die vorhandenen Daten zeigen, dass dem nicht so ist, wird scheitern. Wer sich aber als Dienstleister in seinem Segment versteht, wird erfolgreich sein.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/section><section id=\"777\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid  vc_custom_1560785302049 wow fadeIn vc_row-has-fill pofo-stretch-content vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-has-fill vc_col-sm-12 vc_col-md-6 vc_col-xs-12 wow slideInLeft pofo-column-responsive-6a050554b66e3\" data-wow-delay= 100ms><div class=\"vc_column-inner cover-background bg-position-center-center vc_custom_1585146357280\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-6 vc_col-xs-12 wow slideInRight sm-text-center\" data-wow-delay= 100ms><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><div class=\" vc_custom_1585150579545 last-paragraph-no-margin pofo-text-block-responsive-6a050554b67c8\" style=\"color: #ffffff;\"><h6><strong>Zugegeben: Auch mir f\u00e4llt es manchmal schwer, Dienstleister f\u00fcr meine Leserinnen und Leser zu sein.<\/strong><\/h6>\n<p>Wenn die am besten geklickten Artikel \u00fcber Monate hinweg immer nur Berichte zu Influencer- und Bloggerthemen sind, kann ich diesem Interesse nicht mehr mit Begeisterung folgen. Anderseits trifft es mich, wenn in meinen Augen wichtige Studien zu Nachhaltigkeitsthemen in der Gunst der Abonnenten oft ziemlich durchfallen.<\/p>\n<p>Machen wir es also konkret: Was interessiert die Menschen, die in der heimischen Tourismusbranche ihr Geld verdienen? TN-Deutschland wertet in regelm\u00e4\u00dfigen Abst\u00e4nden alle weiterf\u00fchrenden Links aus dem Newsletter und alle selbst verfassten Artikel auf der Website aus, ordnet die Artikel Themenkomplexen zu und ermittelt so, was die Zielgruppen wirklich interessiert.<\/p>\n<\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section class=\"vc_row wpb_row vc_row-fluid  vc_custom_1585218146404 wow fadeIn\"><div class=\"wpb_column vc_column_container vc_col-md-1 vc_hidden-sm vc_hidden-xs col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-10 vc_col-xs-12\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><div class=\" vc_custom_1585218121830 last-paragraph-no-margin\"><p>2019 \u00fcberragten beim Leserinteresse der Deutschlandtouristiker drei Themenkomplexe: Open Data, Influencer-Marketing und Veranstalter. Das Thema Open Data wirkte dabei wie ein T\u00fcr\u00f6ffner auch f\u00fcr andere Technologiethemen, wie beispielsweise Onlinevertrieb und Website, Mobile Payment oder digitale Services wie eLearning oder Progressive Web App (PWA). Das Thema Influencer wurde interessanterweise immer dann am besten geklickt, wenn der Tenor des Teasers auf das baldige Ende des Hypes hindeutete. Dass das Veranstalterthema 2019 so gut lief, \u201everdanken\u201c wohl alle Travel-Fachmedien der Thomas-Cook-Insolvenz. Der Newsletter mit dem Titel \u201eThomas Cook ist pleite\u201c katapultierte unsere \u00d6ffnungsquote jedenfalls in neue Sph\u00e4ren.<\/p>\n<\/div><div class=\"last-paragraph-no-margin\" style=\"color: #000000;\"><h6><strong>Die zehn meist gelesenen Themenkomplexe auf einen Blick:<\/strong><\/h6>\n<\/div><div class=\"last-paragraph-no-margin\"><ol>\n<li>Open Data &amp; Travel-Technologie<\/li>\n<li>Influencer-Marketing<\/li>\n<li>Veranstalter &amp; Reisevertrieb<\/li>\n<li>Onlinemarketing (SEO, Facebook, Website etc.)<\/li>\n<li>Rechtsthemen (Urteile)<\/li>\n<li>Downloadlinks zu LMO-Praxisleitf\u00e4den<\/li>\n<li>Skandal\u00f6ses (Bad Harzburg erntet herbe Kritik fu\u0308r Werbeaktion mit Busen etc.)<\/li>\n<li>Experten-Interviews<\/li>\n<li>Downloads zu Mafo-Studien<\/li>\n<li>F\u00f6rderprogramme<\/li>\n<\/ol>\n<\/div><div class=\"last-paragraph-no-margin\" style=\"color: #000000;\"><h6><strong>Die zehn am schlechtesten gelesenen Themenkomplexe auf einen Blick:<\/strong><\/h6>\n<\/div><div class=\"last-paragraph-no-margin\"><ol>\n<li>Hotelthemen<\/li>\n<li>Tourismuspolitik<\/li>\n<li>Monats- und Quartalsbilanzen (\u00dcbernachtungszahlen aus den Regionen)<\/li>\n<li>Ausf\u00fchrungen zu Tourismuskonzepten<\/li>\n<li>Kulturthemen (Lutherjahr, Bauhaus etc.)<\/li>\n<li>Nachhaltigkeit<\/li>\n<li>Personalwechsel (Neue Gesch\u00e4ftsf\u00fchrung etc.)<\/li>\n<li>Incoming (weil weiterf\u00fchrende Links oft auf Englisch)<\/li>\n<li>Barrierefreiheit<\/li>\n<li>Zertifizierungen<\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-md-1 vc_hidden-sm vc_hidden-xs col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-lg-1 vc_hidden-sm vc_hidden-xs col-xs-mobile-fullwidth\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/section><section data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid  vc_custom_1507702290365 wow fadeIn vc_row-has-fill pofo-stretch-content vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-6 vc_col-xs-12 wow slideInLeft sm-text-center\" data-wow-delay= 100ms><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><div class=\" vc_custom_1585150733237 last-paragraph-no-margin pofo-text-block-responsive-6a050554b6dc3\" style=\"color: #ffffff;\"><blockquote class=\"border-color-deep-pink\"><p>\nWas jetzt aber tun mit diesem Wissen?\u00a0Nur noch Themen aufbereiten, die gut ziehen? Alles, was weniger gut geklickt wird, aussortieren?\n<\/p><\/blockquote>\n<p>Ich denke das w\u00e4re falsch. Genau wie es fu\u0308r eine Destination falsch w\u00e4re, au\u00dferhalb der Ferienzeiten nur noch Angebote und Themen fu\u0308r Senioren zu kommunizieren, weil die Mehrheit der G\u00e4ste dann vielerorts 60+ ist. Der Wunsch nach zielgruppenspezifischer Kommunikation und Spezialisierung darf nicht in die Eint\u00f6nigkeit f\u00fchren. Spezialisierung darf nie so stark beschneiden, dass auf neue Entwicklungen nur noch in einer Art und Weise reagiert werden kann, die von au\u00dfen betrachtet k\u00fcnstlich und konstruiert wirkt.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-has-fill vc_col-sm-12 vc_col-md-6 vc_col-xs-12 wow slideInRight pofo-column-responsive-6a050554b6ea2\" data-wow-delay= 100ms><div class=\"vc_column-inner cover-background bg-position-center-center vc_custom_1585214871878\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section class=\"vc_row wpb_row vc_row-fluid  vc_custom_1507702414657 wow fadeIn\"><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-md-10 vc_col-xs-12 xs-text-center\"><div class=\"vc_column-inner vc_custom_1504503734313\"><div class=\"wpb_wrapper\"><div class=\"last-paragraph-no-margin\"><p>Besser sollte man mit dem Wissen \u00fcber seine G\u00e4ste bzw. Leser sein Handeln regelm\u00e4\u00dfig reflektieren und sein Produkt mit Fingerspitzengef\u00fchl anpassen. Schrittweise. So, dass Weiterentwicklung nach au\u00dfen und innen erkennbar wird \u2013 aber m\u00f6glichst wenige vom Wandel verschreckt werden. Die im Zuge der Digitalisierung vielfach geforderte Radikalit\u00e4t und Umbaugeschwindigkeit von Firmen und Organisationen kann hier zur Falle werden. Die immer wieder geforderte Kundenzentriertheit st\u00f6\u00dft n\u00e4mlich dann an ihre Grenze, wenn man als Macher, Leistungstr\u00e4ger, Inhaber oder Gesch\u00e4ftsf\u00fchrer einer Tourismusorganisation die datengest\u00fctzten Ergebnisse nicht mehr mit den eigenen Vorstellungen in Einklang bekommt.<\/p>\n<p>Dann lohnt auch mal der Blick zur\u00fcck. Denn Daten sind zwar heute f\u00fcr den Erfolg unverzichtbar \u2013 aber kein Allheilmittel. Erfolg kommt nicht nur zustande, wenn man immer nur das anbietet, von dem man meint, dass es erwartet wird. Sondern besonders auch dann, wenn man \u00fcberraschen kann, sich traut, Dinge selbst zu gestalten. Schon ein mutiger Hotelier kann das Gesicht eines Ortes und dessen G\u00e4stestruktur sehr schnell komplett ver\u00e4ndern. Dann mu\u0308ssen neue Daten her. Es ist der neue ewige Kreislauf.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-1 vc_hidden-sm col-xs-mobile-fullwidth sm-display-none\"><div class=\"vc_column-inner \"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"Wer als Produzent von Content diesen regelm\u00e4\u00dfig auf seinen Erfolg \u00fcberpr\u00fcft, wird um Ver\u00e4nderungen nicht herumkommen. Gleiches gilt fu\u0308r Destinationen, die \u00fcber Daten heute immer mehr \u00fcber ihre G\u00e4ste erfahren. Doch wohin f\u00fchrt das eigentlich? Wissen Sie, was der Niedergang der alten Medienwelt mit der Digitalisierung zu tun hat? Nichts. Vielmehr sind die immensen Auflagenverluste der vergangenen gut zehn Jahre und die sich daran anschlie\u00dfende Unf\u00e4higkeit, die \u201everloren gegangenen Leser\u201c in den Digitalangeboten wieder f\u00fcr sich zu gewinnen, die Geschichte einer Entfremdung. Einer Entfremdung zwischen jenen, die Inhalte produzieren und jenen, die sie lesen (sollen). Ich durfte das als Redaktionsleiter Reise bei der Funke Mediengruppe zwischen 2009 und 2016 in NRW hautnah miterleben. Wenn wir aus dem Reisebereich bei den Kollegen anderer Redaktionen anklopften, ob man dort f\u00fcr uns mal eine Leserreise begleiten k\u00f6nnte, um dar\u00fcber zu schreiben, kam die Absage stets prompt. Einen oder gar mehrere Tage mit den eigenen Lesern zu verbringen \u2013 f\u00fcr die allermeisten Redakteure ein Alptraum! Und so kommt es, dass Edelfedern \u00fcber Theaterpremieren schreiben, die zwar bei den Kollegen in der eigenen Redaktion Begeisterungsst\u00fcrme ausl\u00f6sen, die Leserschaft aber nicht interessieren. Deswegen entstehen Gastrokritiken von Lokalen, in die sich der Gro\u00dfteil der eigenen Abonnenten nie...","protected":false},"author":33,"featured_media":23552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":[],"categories":[62,277],"tags":[164,284,110,57,104,79],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Daten. Inhalte. - neusta tourism Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daten. Inhalte. - neusta tourism Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\" \/>\n<meta property=\"og:site_name\" content=\"neusta tourism Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/neustadestinationsolutions\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T09:48:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-26T10:22:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/vorschau-2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1304\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Leetz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Leetz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\"},\"author\":{\"name\":\"Christian Leetz\",\"@id\":\"https:\/\/www.destination.one\/blog\/#\/schema\/person\/6d85064f1f388e61dd9894d29f2d839c\"},\"headline\":\"Daten. Inhalte.\",\"datePublished\":\"2020-03-26T09:48:50+00:00\",\"dateModified\":\"2020-03-26T10:22:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\"},\"wordCount\":1650,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.destination.one\/blog\/#organization\"},\"keywords\":[\"Content\",\"Daten\",\"Datens\u00e4tze\",\"Digitalisierung\",\"Open Data\",\"Tourismus\"],\"articleSection\":[\"Digitalisierung\",\"tourism.report\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\",\"url\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\",\"name\":\"Daten. Inhalte. - neusta tourism Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.destination.one\/blog\/#website\"},\"datePublished\":\"2020-03-26T09:48:50+00:00\",\"dateModified\":\"2020-03-26T10:22:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.destination.one\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daten. Inhalte.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.destination.one\/blog\/#website\",\"url\":\"https:\/\/www.destination.one\/blog\/\",\"name\":\"neusta tourism Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.destination.one\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.destination.one\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.destination.one\/blog\/#organization\",\"name\":\"neusta destination solutions\",\"url\":\"https:\/\/www.destination.one\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.destination.one\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.neusta-ds.de\/blog\/wp-content\/uploads\/2018\/11\/footer-logo.png\",\"contentUrl\":\"https:\/\/www.neusta-ds.de\/blog\/wp-content\/uploads\/2018\/11\/footer-logo.png\",\"width\":320,\"height\":97,\"caption\":\"neusta destination solutions\"},\"image\":{\"@id\":\"https:\/\/www.destination.one\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/neustadestinationsolutions\",\"https:\/\/www.instagram.com\/neusta_ds\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.destination.one\/blog\/#\/schema\/person\/6d85064f1f388e61dd9894d29f2d839c\",\"name\":\"Christian Leetz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.destination.one\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/AnnaMuysersFotografie-3-150x150.jpeg\",\"contentUrl\":\"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/AnnaMuysersFotografie-3-150x150.jpeg\",\"caption\":\"Christian Leetz\"},\"description\":\"Christian Leetz hat Betriebswirtschaft in Frankfurt und Kulturwissenschaften an der Fernuni Hagen studiert. Als freier Journalist schrieb er aus Barcelona f\u00fcr Medien wie S\u00fcddeutsche Zeitung, FAZ und Frankfurter Rundschau. Von 2009 bis 2016 leitete er das Reise- und Beilagen-Ressort der Funke Mediengruppe NRW, bevor er sich 2016 mit TN-Deutschland selbstst\u00e4ndig machte. Bis heute ist er Herausgeber des Newsdienstes und produziert mit Schwerpunkt auf digitale Themen Magazine f\u00fcr DZT und DTV.\",\"url\":\"https:\/\/www.destination.one\/blog\/author\/christian-leetz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daten. Inhalte. - neusta tourism Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/","og_locale":"de_DE","og_type":"article","og_title":"Daten. Inhalte. - neusta tourism Blog","og_url":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/","og_site_name":"neusta tourism Blog","article_publisher":"https:\/\/www.facebook.com\/neustadestinationsolutions","article_published_time":"2020-03-26T09:48:50+00:00","article_modified_time":"2020-03-26T10:22:30+00:00","og_image":[{"width":1304,"height":684,"url":"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/vorschau-2-2.jpg","type":"image\/jpeg"}],"author":"Christian Leetz","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Leetz","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#article","isPartOf":{"@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/"},"author":{"name":"Christian Leetz","@id":"https:\/\/www.destination.one\/blog\/#\/schema\/person\/6d85064f1f388e61dd9894d29f2d839c"},"headline":"Daten. Inhalte.","datePublished":"2020-03-26T09:48:50+00:00","dateModified":"2020-03-26T10:22:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/"},"wordCount":1650,"commentCount":0,"publisher":{"@id":"https:\/\/www.destination.one\/blog\/#organization"},"keywords":["Content","Daten","Datens\u00e4tze","Digitalisierung","Open Data","Tourismus"],"articleSection":["Digitalisierung","tourism.report"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/","url":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/","name":"Daten. Inhalte. - neusta tourism Blog","isPartOf":{"@id":"https:\/\/www.destination.one\/blog\/#website"},"datePublished":"2020-03-26T09:48:50+00:00","dateModified":"2020-03-26T10:22:30+00:00","breadcrumb":{"@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.destination.one\/blog\/daten-inhalte\/tourism-report\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.destination.one\/blog\/"},{"@type":"ListItem","position":2,"name":"Daten. Inhalte."}]},{"@type":"WebSite","@id":"https:\/\/www.destination.one\/blog\/#website","url":"https:\/\/www.destination.one\/blog\/","name":"neusta tourism Blog","description":"","publisher":{"@id":"https:\/\/www.destination.one\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.destination.one\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.destination.one\/blog\/#organization","name":"neusta destination solutions","url":"https:\/\/www.destination.one\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.destination.one\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.neusta-ds.de\/blog\/wp-content\/uploads\/2018\/11\/footer-logo.png","contentUrl":"https:\/\/www.neusta-ds.de\/blog\/wp-content\/uploads\/2018\/11\/footer-logo.png","width":320,"height":97,"caption":"neusta destination solutions"},"image":{"@id":"https:\/\/www.destination.one\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/neustadestinationsolutions","https:\/\/www.instagram.com\/neusta_ds\/"]},{"@type":"Person","@id":"https:\/\/www.destination.one\/blog\/#\/schema\/person\/6d85064f1f388e61dd9894d29f2d839c","name":"Christian Leetz","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.destination.one\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/AnnaMuysersFotografie-3-150x150.jpeg","contentUrl":"https:\/\/www.destination.one\/blog\/wp-content\/uploads\/2020\/03\/AnnaMuysersFotografie-3-150x150.jpeg","caption":"Christian Leetz"},"description":"Christian Leetz hat Betriebswirtschaft in Frankfurt und Kulturwissenschaften an der Fernuni Hagen studiert. Als freier Journalist schrieb er aus Barcelona f\u00fcr Medien wie S\u00fcddeutsche Zeitung, FAZ und Frankfurter Rundschau. Von 2009 bis 2016 leitete er das Reise- und Beilagen-Ressort der Funke Mediengruppe NRW, bevor er sich 2016 mit TN-Deutschland selbstst\u00e4ndig machte. Bis heute ist er Herausgeber des Newsdienstes und produziert mit Schwerpunkt auf digitale Themen Magazine f\u00fcr DZT und DTV.","url":"https:\/\/www.destination.one\/blog\/author\/christian-leetz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/posts\/23541"}],"collection":[{"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/comments?post=23541"}],"version-history":[{"count":9,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/posts\/23541\/revisions"}],"predecessor-version":[{"id":23556,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/posts\/23541\/revisions\/23556"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/media\/23552"}],"wp:attachment":[{"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/media?parent=23541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/categories?post=23541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.destination.one\/blog\/wp-json\/wp\/v2\/tags?post=23541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}